{"id":13,"date":"2025-11-12T06:30:15","date_gmt":"2025-11-12T06:30:15","guid":{"rendered":"https:\/\/handyservice.wordpressdemo.in\/?page_id=13"},"modified":"2025-11-14T10:01:06","modified_gmt":"2025-11-14T10:01:06","slug":"home","status":"publish","type":"page","link":"https:\/\/handyservice.wordpressdemo.in\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13\" class=\"elementor elementor-13\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e19057 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e19057\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d312582\" data-id=\"d312582\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3eeec0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a3eeec0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TRUSTED HANDYMAN SERVICES<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64a407b elementor-widget elementor-widget-heading\" data-id=\"64a407b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Best Professionals Handyman Solution\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8997cda elementor-widget elementor-widget-text-editor\" data-id=\"8997cda\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"bf794ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><p>Fusce ea commodo feugiat volutpat ipsum incidunt, consequuntur accumsan cupidatat, vitae felis, sociis nisi minima nascetur expedita. Lacus habitant exercitationem molestie neque volutpat venenatis lorem.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-popup-target elementor-element elementor-element-e9f95e8 elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-jet-popup=\"{&quot;attached-popup&quot;:&quot;jet-popup-60&quot;,&quot;trigger-type&quot;:&quot;click-self&quot;,&quot;trigger-custom-selector&quot;:&quot;&quot;}\" data-id=\"e9f95e8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GET APPOINTMENT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ae2de3b\" data-id=\"ae2de3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36a0a90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36a0a90\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a5996d\" data-id=\"5a5996d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c4de4e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4de4e4\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9ad420d\" data-id=\"9ad420d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7112a4d elementor-widget elementor-widget-image\" data-id=\"7112a4d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"560\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image3.jpg\" class=\"attachment-large size-large wp-image-97\" alt=\"\" srcset=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image3.jpg 300w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image3-161x300.jpg 161w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d16a540\" data-id=\"d16a540\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b1496 elementor-widget elementor-widget-image\" data-id=\"34b1496\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"560\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image2.jpg\" class=\"attachment-large size-large wp-image-95\" alt=\"\" srcset=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image2.jpg 300w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image2-161x300.jpg 161w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d8ca83e\" data-id=\"d8ca83e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68096db elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"68096db\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ABOUT OUR COMPANY<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f1652f elementor-widget elementor-widget-heading\" data-id=\"3f1652f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Providing Quality &amp; Experienced Service\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dba9e6e elementor-widget elementor-widget-text-editor\" data-id=\"dba9e6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"bf794ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><p>Fusce ea commodo feugiat volutpat ipsum incidunt, consequuntur accumsan cupidatat, vitae felis, sociis nisi minima nascetur expedita. Lacus habitant exercitationem molestie neque volutpat venenatis lorem.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a55af2 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5a55af2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Request &amp; Scheduling<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Evaluation &amp; Estimate<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Expert Service &amp; Follow-Up<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d7d172 elementor-widget elementor-widget-button\" data-id=\"3d7d172\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/handyservice.wordpressdemo.in\/index.php\/about-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MORE ABOUT US<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47c3622 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47c3622\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-393b1fb\" data-id=\"393b1fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2679466 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2679466\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WHY CHOOSE US ?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d3bc22 elementor-widget elementor-widget-heading\" data-id=\"0d3bc22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trusted Experts for All-Inclusive Handyman Services\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fed3742 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fed3742\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2f0cffa\" data-id=\"2f0cffa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c053d61 elementor-widget elementor-widget-jet-banner\" data-id=\"c053d61\" data-element_type=\"widget\" data-widget_type=\"jet-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-banner jet-elements\"><figure class=\"jet-banner jet-effect-lily\"><div class=\"jet-banner__overlay\"><\/div><img decoding=\"async\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image10.jpg\" alt=\"image10\" width=\"100%\" height=\"100%\" class=\"jet-banner__img\"><figcaption class=\"jet-banner__content\"><div class=\"jet-banner__content-wrap\"><h5 class=\"jet-banner__title\">Electrical Repair Services<\/h5><\/div><\/figcaption><\/figure>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-216f54b\" data-id=\"216f54b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91401bb elementor-widget elementor-widget-jet-banner\" data-id=\"91401bb\" data-element_type=\"widget\" data-widget_type=\"jet-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-banner jet-elements\"><figure class=\"jet-banner jet-effect-lily\"><div class=\"jet-banner__overlay\"><\/div><img decoding=\"async\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image5.jpg\" alt=\"image5\" width=\"100%\" height=\"100%\" class=\"jet-banner__img\"><figcaption class=\"jet-banner__content\"><div class=\"jet-banner__content-wrap\"><h5 class=\"jet-banner__title\">Air Conditioning Services<\/h5><\/div><\/figcaption><\/figure>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-255a0a8\" data-id=\"255a0a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2a6b89 elementor-widget elementor-widget-jet-banner\" data-id=\"a2a6b89\" data-element_type=\"widget\" data-widget_type=\"jet-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-banner jet-elements\"><figure class=\"jet-banner jet-effect-lily\"><div class=\"jet-banner__overlay\"><\/div><img decoding=\"async\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image6.jpg\" alt=\"image6\" width=\"100%\" height=\"100%\" class=\"jet-banner__img\"><figcaption class=\"jet-banner__content\"><div class=\"jet-banner__content-wrap\"><h5 class=\"jet-banner__title\">Home Painting And Decoration<\/h5><\/div><\/figcaption><\/figure>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48ea33a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48ea33a\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f43509e\" data-id=\"f43509e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e57ca6 elementor-widget elementor-widget-jet-banner\" data-id=\"8e57ca6\" data-element_type=\"widget\" data-widget_type=\"jet-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-banner jet-elements\"><figure class=\"jet-banner jet-effect-lily\"><div class=\"jet-banner__overlay\"><\/div><img decoding=\"async\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9.jpg\" alt=\"image9\" width=\"100%\" height=\"100%\" class=\"jet-banner__img\"><figcaption class=\"jet-banner__content\"><div class=\"jet-banner__content-wrap\"><h5 class=\"jet-banner__title\">Residental Plumbing Services<\/h5><\/div><\/figcaption><\/figure>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-48f8d06\" data-id=\"48f8d06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-916832a elementor-widget elementor-widget-jet-banner\" data-id=\"916832a\" data-element_type=\"widget\" data-widget_type=\"jet-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-banner jet-elements\"><figure class=\"jet-banner jet-effect-lily\"><div class=\"jet-banner__overlay\"><\/div><img decoding=\"async\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image7.jpg\" alt=\"image7\" width=\"100%\" height=\"100%\" class=\"jet-banner__img\"><figcaption class=\"jet-banner__content\"><div class=\"jet-banner__content-wrap\"><h5 class=\"jet-banner__title\">Custom Carpentry Services<\/h5><\/div><\/figcaption><\/figure>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b83924c\" data-id=\"b83924c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddfc7de elementor-widget elementor-widget-jet-banner\" data-id=\"ddfc7de\" data-element_type=\"widget\" data-widget_type=\"jet-banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-banner jet-elements\"><figure class=\"jet-banner jet-effect-lily\"><div class=\"jet-banner__overlay\"><\/div><img decoding=\"async\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image8.jpg\" alt=\"image8\" width=\"100%\" height=\"100%\" class=\"jet-banner__img\"><figcaption class=\"jet-banner__content\"><div class=\"jet-banner__content-wrap\"><h5 class=\"jet-banner__title\">General Renovation Services<\/h5><\/div><\/figcaption><\/figure>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-706fec3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"706fec3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/(556)%20589-3366\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HIRE US NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5868af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5868af\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21b1b0c\" data-id=\"21b1b0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0b2515 elementor-widget elementor-widget-jet-testimonials\" data-id=\"b0b2515\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;}\" data-widget_type=\"jet-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-testimonials jet-elements\">\n<div class=\"jet-testimonials\">\n\t<div class=\"jet-testimonials__instance elementor-slick-slider\"data-settings='{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;centerMode&quot;:false,&quot;centerPadding&quot;:&quot;50px&quot;,&quot;adaptiveHeight&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:false,&quot;dots&quot;:true,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;.jet-testimonial__prev-arrow-b0b2515&quot;,&quot;nextArrow&quot;:&quot;.jet-testimonial__next-arrow-b0b2515&quot;,&quot;rtl&quot;:false}' dir=\"ltr\"><div class=\"jet-testimonials__item\">\n\t<div class=\"jet-testimonials__item-inner\">\n\t\t\t\t<div class=\"jet-testimonials__content\"><figure class=\"jet-testimonials__figure\"><img decoding=\"async\" class=\"jet-testimonials__tag-img\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/reviews-img1.png\" alt=\"reviews-img1\" loading=\"lazy\"><\/figure><div class=\"jet-testimonials__comment\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna.<\/div><div class=\"jet-testimonials__name\"><span>Mary Scott<\/span><\/div><\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"jet-testimonials__item\">\n\t<div class=\"jet-testimonials__item-inner\">\n\t\t\t\t<div class=\"jet-testimonials__content\"><figure class=\"jet-testimonials__figure\"><img decoding=\"async\" class=\"jet-testimonials__tag-img\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/reviews-img1.png\" alt=\"reviews-img1\" loading=\"lazy\"><\/figure><div class=\"jet-testimonials__comment\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna.<\/div><div class=\"jet-testimonials__name\"><span>Mary Scott<\/span><\/div><\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"jet-testimonials__item\">\n\t<div class=\"jet-testimonials__item-inner\">\n\t\t\t\t<div class=\"jet-testimonials__content\"><figure class=\"jet-testimonials__figure\"><img decoding=\"async\" class=\"jet-testimonials__tag-img\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/reviews-img1.png\" alt=\"reviews-img1\" loading=\"lazy\"><\/figure><div class=\"jet-testimonials__comment\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna.<\/div><div class=\"jet-testimonials__name\"><span>Mary Scott<\/span><\/div><\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"jet-testimonials__item\">\n\t<div class=\"jet-testimonials__item-inner\">\n\t\t\t\t<div class=\"jet-testimonials__content\"><figure class=\"jet-testimonials__figure\"><img decoding=\"async\" class=\"jet-testimonials__tag-img\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/reviews-img1.png\" alt=\"reviews-img1\" loading=\"lazy\"><\/figure><div class=\"jet-testimonials__comment\">Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua.Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna.<\/div><div class=\"jet-testimonials__name\"><span>Mary Scott<\/span><\/div><\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-98a132b\" data-id=\"98a132b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-287ce4e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"287ce4e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CLIENT REVIEWS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d67efec elementor-widget elementor-widget-heading\" data-id=\"d67efec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Checkout What Our Clients Says..\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a83cf elementor-widget elementor-widget-text-editor\" data-id=\"80a83cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"bf794ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><p>Fusce ea commodo feugiat volutpat ipsum incidunt, consequuntur accumsan cupidatat, vitae felis, sociis nisi minima nascetur expedita. Lacus habitant exercitationem molestie neque volutpat venenatis lorem.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-popup-target elementor-element elementor-element-c217992 elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-jet-popup=\"{&quot;attached-popup&quot;:&quot;jet-popup-60&quot;,&quot;trigger-type&quot;:&quot;click-self&quot;,&quot;trigger-custom-selector&quot;:&quot;&quot;}\" data-id=\"c217992\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GET APPOINTMENT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2552f48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2552f48\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03372be\" data-id=\"03372be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfb9ddf elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dfb9ddf\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm113.9 231L234.4 103.5c-9.4-9.4-24.6-9.4-33.9 0l-17 17c-9.4 9.4-9.4 24.6 0 33.9L285.1 256 183.5 357.6c-9.4 9.4-9.4 24.6 0 33.9l17 17c9.4 9.4 24.6 9.4 33.9 0L369.9 273c9.4-9.4 9.4-24.6 0-34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WORK GALLERY<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03b767b elementor-widget elementor-widget-heading\" data-id=\"03b767b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Latest Work Gallery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d90dc5f gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"d90dc5f\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-13 gallery-columns-3 gallery-size-kava-thumb-m'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d90dc5f\" data-elementor-lightbox-title=\"image9\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExLCJ1cmwiOiJodHRwczpcL1wvaGFuZHlzZXJ2aWNlLndvcmRwcmVzc2RlbW8uaW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9pbWFnZTkuanBnIiwic2xpZGVzaG93IjoiZDkwZGM1ZiJ9\" href='https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9.jpg'><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9-400x400.jpg\" class=\"attachment-kava-thumb-m size-kava-thumb-m\" alt=\"\" srcset=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9-400x400.jpg 400w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9-300x300.jpg 300w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9-150x150.jpg 150w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9-230x230.jpg 230w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/image9.jpg 500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d90dc5f\" data-elementor-lightbox-title=\"plumbero-img22\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA5LCJ1cmwiOiJodHRwczpcL1wvaGFuZHlzZXJ2aWNlLndvcmRwcmVzc2RlbW8uaW5cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzExXC9wbHVtYmVyby1pbWcyMi5qcGciLCJzbGlkZXNob3ciOiJkOTBkYzVmIn0%3D\" href='https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img22.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img22-400x400.jpg\" class=\"attachment-kava-thumb-m size-kava-thumb-m\" alt=\"\" srcset=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img22-400x400.jpg 400w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img22-150x150.jpg 150w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img22-230x230.jpg 230w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img22-640x640.jpg 640w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d90dc5f\" data-elementor-lightbox-title=\"plumbero-img24\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzAsInVybCI6Imh0dHBzOlwvXC9oYW5keXNlcnZpY2Uud29yZHByZXNzZGVtby5pblwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMTFcL3BsdW1iZXJvLWltZzI0LmpwZyIsInNsaWRlc2hvdyI6ImQ5MGRjNWYifQ%3D%3D\" href='https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img24.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img24-400x400.jpg\" class=\"attachment-kava-thumb-m size-kava-thumb-m\" alt=\"\" srcset=\"https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img24-400x400.jpg 400w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img24-150x150.jpg 150w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img24-230x230.jpg 230w, https:\/\/handyservice.wordpressdemo.in\/wp-content\/uploads\/2025\/11\/plumbero-img24-640x640.jpg 640w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TRUSTED HANDYMAN SERVICES Best Professionals Handyman Solution Fusce ea commodo feugiat volutpat ipsum incidunt, consequuntur accumsan cupidatat, vitae felis, sociis nisi minima nascetur expedita. Lacus habitant exercitationem molestie neque volutpat venenatis lorem. GET APPOINTMENT ABOUT OUR COMPANY Providing Quality &amp; Experienced Service Fusce ea commodo feugiat volutpat ipsum incidunt, consequuntur accumsan cupidatat, vitae felis, sociis [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","_joinchat":[],"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":61,"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":163,"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/pages\/13\/revisions\/163"}],"wp:attachment":[{"href":"https:\/\/handyservice.wordpressdemo.in\/index.php\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}